{"id":7107,"date":"2017-06-08T11:47:57","date_gmt":"2017-06-08T10:47:57","guid":{"rendered":"https:\/\/www.jocelyne-lopez.de\/blog\/?p=7107"},"modified":"2017-06-09T12:10:16","modified_gmt":"2017-06-09T11:10:16","slug":"affenhirnforscher-prof-hans-peter-thier-stellvertreter-eines-lobbyismus-netzwerks-jenseits-der-gesetze-beim-rektor-prof-bernd-engler","status":"publish","type":"post","link":"https:\/\/www.jocelyne-lopez.de\/blog\/2017\/06\/affenhirnforscher-prof-hans-peter-thier-stellvertreter-eines-lobbyismus-netzwerks-jenseits-der-gesetze-beim-rektor-prof-bernd-engler\/","title":{"rendered":"Affenhirnforscher Prof. Hans-Peter Thier: Stellvertreter eines Lobbyismus-Netzwerks jenseits der Gesetze beim Rektor Prof. Bernd Engler?"},"content":{"rendered":"<p style=\"text-align: justify;\">Unsere <a href=\"https:\/\/www.jocelyne-lopez.de\/pdfDateien\/Dienstaufsichtsbeschwerde%20Hans%20Peter%20Thier%2015_04_2017.pdf\">Dienstaufsichtsbeschwerde \u00fcber Prof. Hans-Peter Thier<\/a>\u00a0 wegen Verdacht auf illegale Versuche mit Primaten liegt jetzt auf dem Tisch des Rektors der Universit\u00e4t T\u00fcbingen, Prof. Bernd Engler, nach einer Wanderung seit der 15. April 2017 \u00fcber verschiedene involvierte Verwaltungsstellen \u00a0bei dieser extrem verstrickten und intransparenten Forschung (Hertie Stiftung,\u00a0 Regierungspr\u00e4sidium Darmstadt, Wissenschaftsministerium Baden-W\u00fcrttemberg), die sich alle als nicht zust\u00e4ndig herausgewunden\u00a0haben &#8211; wohlbemerkt ohne die zust\u00e4ndige Stelle zu nennen. Das Grundprinzip &#8222;<em>von Poncius zu Pilatus schicken<\/em>&#8220; wird gerne bei Verwaltung und Politik gegen die B\u00fcrger angewandt&#8230; Wir wurden schlie\u00dflich am 02.06.2017\u00a0 vom <a href=\"https:\/\/www.jocelyne-lopez.de\/blog\/2017\/06\/unsere-dienstsaufsichtbeschwerde-ueber-prof-hans-peter-thier-ist-jetzt-beim-rektor-der-uni-tuebingen-prof-bernd-engler-gelandet\/\">Dezernat \u00a0\u201e<em>Forschung, Strategie und Recht<\/em>\u201c<\/a> der Universit\u00e4t T\u00fcbingen informiert, dass der Rektor Prof. Bernd Engler gedenkt, unsere Dienstaufsichtsbeschwerde in den n\u00e4chsten zwei Wochen zu beantworten.<\/p>\n<p style=\"text-align: justify;\">Wir sind sehr gespannt zu erfahren wie Prof. Bernd Engler in zwei Wochen diesen komplexen Sachverhalt pr\u00fcfen und bescheiden wird, nachdem er seit mindestens 10 Jahren grobfahrl\u00e4ssig vers\u00e4umt hat zu pr\u00fcfen, was f\u00fcr eine \u201e<em>Forschung<\/em>\u201c im Rahmen seines omin\u00f6sen, staatlich subventionierten \u201e<em>Exzellenz-Clusters f\u00fcr integrierte Hirnforschung<\/em>\u201c\u00a0\u00a0durch Prof. Hans-Peter Thier &amp; Co. betrieben wird.<\/p>\n<p style=\"text-align: justify;\">Unter dem Deckmantel der medizinischen Forschung zu Therapieans\u00e4tzen von menschlichen neurologischen oder psychiatrischen Erkrankungen wie Alzheimer, Parkinson, Epilepsie, Multiple Sklerose oder Schizophrenie hat n\u00e4mlich insbesondere Prof. Hans-Peter Thier ein gigantisches Netzwerk aufgebaut, um Abermillionen \u00a0von Steuergeldern f\u00fcr die medizinische Forschung zu ergattern, wie er es selbst in der Presse mit gespielter Bescheidenheit verk\u00fcndet:<\/p>\n<p style=\"padding-left: 30px;\"><a href=\"http:\/\/www.tagblatt.de\/Nachrichten\/Der-Vater-des-Exzellenz-Clusters-fuer-integrierte-Hirnforschung-156852.html\"><strong>17.05.2012 Schw\u00e4bisches Tagblatt &#8211; Neuro-Netzwerker Hans-Peter Thier &#8211; Der Vater des Exzellenz-Clusters f\u00fcr integrierte Hirnforschung <\/strong><\/a><\/p>\n<p style=\"text-align: justify; padding-left: 30px;\">[&#8230;] <em>Dass T\u00fcbingen innerhalb weniger Jahre ein Spitzenzentrum neuro-wissenschaftlicher Forschung wurde, ist nicht zuletzt das Werk von Hans-Peter Thier. Der Neurologe und Direktor am Hertie- Institut ist auch der Kopf hinter dem interdisziplin\u00e4ren \u201eCluster\u201c CIN, dessen Neubau jetzt er\u00f6ffnet wird. <\/em><\/p>\n<p style=\"text-align: justify; padding-left: 30px;\"><em>\u00a0\u201eJa, ich bin der arme Mensch, der den Antrag f\u00fcr das Centrum f\u00fcr Integrative Neurowissenschaften geschrieben hat\u201c, sagt Hans-Peter Thier mit dem f\u00fcr ihn typischen ironischen Understatement. Thier hat aber nicht nur den Forschungsverbund der T\u00fcbinger Uni konzipiert, der als einziger in der ersten Exzellenz-Initiative 2007 erfolgreich war. Er war auch der Headhunter, der \u00fcber die Jahre die besten K\u00f6pfe aus der Neurowissenschaft umwarb, nach T\u00fcbingen zu kommen, international bekannte Namen wie den Parkinson-Forscher Thomas Gasser oder den Schlafforscher und Leibniz-Preistr\u00e4ger Jan Born.<\/em>\u201c [&#8230;]<\/p>\n<p style=\"text-align: justify;\">Obwohl seit mehr als 40 Jahren mit Millionen und Milliarden von Steuergeldern in 11 Forschungsstandorten (Frankfurt, Bremen, Berlin, M\u00fcnchen, G\u00f6ttingen, Bochum, Marburg, Magdeburg sowie 3 Forschungsinstitute in T\u00fcbingen) die Affenhirnforscher keine einzige brauchbare neue Erkenntnis zur Therapie der angegebenen menschlichen Erkrankungen nachzuweisen haben, ist es Prof. Hans-Peter Thier 2013 mit seinem Kollegen Prof. Stefan Treue aus G\u00f6ttingen ohne weiteres noch gelungen, eine zus\u00e4tzliche millionenschwere staatliche F\u00f6rderung f\u00fcr eine neue Forschergruppe zur Affenhirnforschung zu ergattern, sie k\u00f6nnen wohl den Hals nie genug voll kriegen: <a href=\"https:\/\/www.change.org\/p\/herr-prof-hans-peter-thier-beantworten-sie-bitte-4-fragen-\u00fcber-den-wissenschaftlichen-wert-der-affenhirnforschung-am-max-planck-institut-mpi-t\u00fcbingen\/u\/13641836\">3,5 Mio Euro Steuergeld f\u00fcr die Gr\u00fcndung 2013 einer neuen Forschergruppe zur Affenhirnforschung<\/a><\/p>\n<p style=\"text-align: justify;\">Seit mehr als 40 Jahren ignorieren auch die Affenhirnforscher, genauso wie der gute Rektor der Universit\u00e4t T\u00fcbingen Prof. Bernd Engler, alle nationalen und internationalen wissenschaftlichen Studien, die nachweisen, dass diese Forschungsmethode mit Tierversuchen methodologisch nicht geeignet ist, irgendwelche brauchbare neue Erkenntnisse f\u00fcr die Humanmedizin zu erzielen, was auch ihre Erfolglosigkeit erkl\u00e4rt.<\/p>\n<p style=\"text-align: justify;\">Die Affenhirnforscher lassen sich von der Erfolglosigkeit ihrer Forschung f\u00fcr die Humanmedizin \u00fcberhaupt nicht st\u00f6ren, sie qu\u00e4len und t\u00f6ten Primaten als reine Besch\u00e4ftigungstherapie (sie ist ja auch extrem lukrativ) sowie aus Karriere- und Mediensucht f\u00fcr\u00a0 ganz andere Ziele als f\u00fcr &#8222;<em>das Wohl der Menschen<\/em>&#8220; wie der Rektor\u00a0 Bernd Engler es glauben lassen will, so zum Beispiel um die Frage zu kl\u00e4ren, wie Fu\u00dfballer Tore schie\u00dfen (Prof. Hans-Peter Thier in T\u00fcbingen), oder wie\u00a0 der Torwart der Fu\u00dfballnationalmannschaft Jens Lehmann bei der WM 2006 gegen Argentinien zwei Elfmeter halten konnte (<a href=\"http:\/\/www.pm.ruhr-uni-bochum.de\/pm2007\/msg00378.htm\">Prof. Klaus-Peter Hoffmann bei der Uni Bochum<\/a> sowie auch die Uni Marburg), oder um die Frage zu kl\u00e4ren, ob Menschen einen freien Willen haben und ob Gott existiert (<a href=\"https:\/\/de.wikipedia.org\/wiki\/Wolf_Singer\">Prof. Wolf Singer in Frankfurt<\/a>), oder um die Fragen zu kl\u00e4ren, ob Primaten ein Bewusstsein haben und wo es sich in ihren Gehirnen befindet (<a href=\"http:\/\/www.swp.de\/ulm\/nachrichten\/suedwestumschau\/tuebinger-affenforscher-erhaelt-auszeichnung-in-griechenland-12285488.html\">Prof. Nikos Logothetis in T\u00fcbingen<\/a>).<\/p>\n<p style=\"text-align: justify;\">Das ist wissenschaftlicher <a href=\"http:\/\/www.spiegel.de\/wissenschaft\/medizin\/lancet-spezial-fuer-mehr-qualitaet-in-der-wissenschaft-a-942328.html\">Forschungsm\u00fcll\u00a0<\/a>\u00a0\u00a0ohne gleichen, sowie auch hochgradige Gesetzwidrigkeit: Solche Experimente sind nach Tierschutzgesetz n\u00e4mlich nicht genehmigungsf\u00e4hig. Kein Wunder, dass der ber\u00fcchtigte Tierqu\u00e4ler vom Max-Planck Institut in Frankfurt und fachlich stark umstrittene\u00a0Hirnforscher, Wolf Singer, \u00a0schon 1990 in den Medien verraten hat, dass die Affenhirnforscher ihre Forschungsantr\u00e4ge f\u00e4lschen m\u00fcssen: <a href=\"http:\/\/www.gegenworte.org\/heft-4\/singer4.html\">Zitat Wolf Singer\u00a0 <\/a>: [&#8230;] \u201e<em>Ja, das sieht man deutlich daran, da\u00df der Gesetzgeber zunehmend die Zuwendung von Mitteln davon abh\u00e4ngig macht, da\u00df wir nachweisen k\u00f6nnen, welche umsetzbaren Erkenntnisse die einzelnen Untersuchungen erbringen werden. Das ist eine Katastrophe. Diese Vorgaben verf\u00fchren die Forscher zum Schwindeln.<\/em>\u201c [&#8230;] F\u00fcr welche Verdienste f\u00fcr die Allgemeinheit sich Wolf Singer \u00fcbrigens <a href=\"https:\/\/www.change.org\/p\/herr-prof-hans-peter-thier-beantworten-sie-bitte-4-fragen-\u00fcber-den-wissenschaftlichen-wert-der-affenhirnforschung-am-max-planck-institut-mpi-t\u00fcbingen\/u\/17932400\">das\u00a0 Bundesverdienstkreuz<\/a>\u00a0\u00a0\u00a0von seinen Freunden aus der Wirtschaft und der Politik 2011 besorgt hat, wei\u00df allerdings kein Mensch und er beantwortet selbst diese Frage nicht &#8211; kann man ja verstehen. Daf\u00fcr, dass er so dezent schweigsam ist bei Fragen \u00fcber seine Forschung, hat er\u00a0als &#8222;<a href=\"http:\/\/www.dfg.de\/gefoerderte_projekte\/wissenschaftliche_preise\/communicator-preis\/2003\/\"><em>Communicator 2003<\/em><\/a>&#8220; von der Deutschen Forschungsgemeinschaft 50.000 Euro Steuergeld abgesahnt, f\u00fcr\u00a0seine \u201e<em>herausragenden Leistungen in der Vermittlung seiner wissenschaftlichen Arbeit in die \u00d6ffentlichkeit&#8220;. <\/em>Ach ja, schon klar, Lobbyismus l\u00e4sst gr\u00fc\u00dfen.<\/p>\n<p style=\"text-align: justify;\">Auch ist die Vermutung nicht abwegig, dass die Affenhirnforscher illegale Experimente an Affen zum Testen von Psychopharmazeutika und Psycho-Drogen durchf\u00fchren. Warum h\u00e4tte sonst der Affenhirnforscher Wolf Singer in einem <a href=\"http:\/\/www.philosophie.uni-mainz.de\/metzinger\/publikationen\/Gehirn%20&amp;%20Geist.htm\">Interview \u00fcber seine Forschung<\/a> \u00a0\u201e<em>das<\/em> <em> ganze Arsenal psychoaktiver Pharmaka \u2013 wobei die Palette der M\u00f6glichkeiten allerdings derzeit enorm anw\u00e4chst\u201c<\/em> erw\u00e4hnt? Was hat er bittesch\u00f6n als Grundlagenforscher an Primaten mit psychoaktiven Pharmaka zu tun?\u00a0 Genauso ist die Vermutung nicht abwegig, dass die Affenhirnforscher illegal f\u00fcr das Milit\u00e4r forschen: Wenn man zum Beispiel in diesem <a href=\"http:\/\/www.tab-beim-bundestag.de\/de\/pdf\/publikationen\/berichte\/TAB-Arbeitsbericht-ab117.pdf\">Bericht \u00fcber die Hirnforschung<\/a> (der sich zuf\u00e4lligerweise als Umschlagsbild ein Bild von einer Hirnforschungsinstitution aus T\u00fcbingen ausgesucht hat) nach dem Sch\u00fcsselwort \u201e<em>milit\u00e4r<\/em>\u201c sucht, findet man viele Treffer f\u00fcr die Nutzung der Hirnforschung beim Milit\u00e4r &#8211; auch f\u00fcr die Nutzung beim Sport, zum Beispiel f\u00fcr Doping. Hat Prof. Hans-Peter Thier, der sich soooo sehr daf\u00fcr interessiert wie Fu\u00dfballer Tore schiessen, in T\u00fcbingen Doping-Substanzen f\u00fcr den Sport bei Affen getestet?<\/p>\n<p style=\"text-align: justify;\">Der unkontrollierte Sumpf der Grundlagenforschung mit Primaten zu angeblichen Therapieans\u00e4tzen von Alzheimer, Parkinson, Epilepsie, Multiple Sklerose oder Schizophrenie stinkt zum Himmel &#8211; als Lobbyismus, als Wissenschaftsbetrug und als Steuerbetrug, jenseits der Menschlichkeit, der ethischen Verantwortung und der Gesetze.<\/p>\n<p style=\"text-align: justify;\">Es ist erschreckend, dass die Universit\u00e4ten, die sich f\u00fcr die \u201eElite\u201c der Gesellschaft halten, sowie die Beh\u00f6rden und die Politik diesen Sumpf erm\u00f6glichen, decken bzw. f\u00f6rdern, sowie zu Lasten der Leiden der Tiere und der Menschen sich mit dieser Gewaltherrschaft eine goldene Nase und Ruhm in den Medien verdienen.<\/p>\n<p style=\"text-align: justify;\">Vor diesem Hintergrund sind wir sehr gespannt wie der gute Rektor der Universit\u00e4t T\u00fcbingen in zwei Wochen unsere Dienstaufsichtsbeschwerde \u00fcber Prof. Hans-Peter Thier pr\u00fcfen und bescheiden wird, die nur die Spitze des Eisberges bei diesem Lobbyismus- und Betrugssystem darstellt &#8211; ein Netzwerk, das er wohlbemerkt selbst wissentlich seit Jahren auf Kosten der Tiere, der Patienten und der Steuerzahler bef\u00fcrwortet und sch\u00fctzt. Wir werden berichten.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/assets.change.org\/photos\/3\/tm\/jb\/GzTmJBYMTtMGadW-800x450-noPad.jpg?1484640649\" width=\"451\" height=\"253\" \/><\/p>\n<h5 style=\"text-align: center;\">Bild: \u00a9 <a href=\"http:\/\/www.fabula-dortmund.de\/pages\/bildergalerien\/galerien-malerei\/aktuelles-01\/aktuelles-26.php\">Atelier Kunstwerk Fabula, Dortmund<\/a><\/h5>\n<h5 style=\"text-align: center;\">Das beigef\u00fcgte Bild &#8222;<em>Was in der Arche \u00fcbrig bleibt<\/em>&#8230;&#8220; der K\u00fcnstlerin Olivia Rost bildet auf der linken Seite die Affenhirnforscher Prof. Hans-Peter Thier und Prof. Stefan Treue ab, sowie auch auf der rechten Seite die Frau Wissenschaftsministerin in Baden-W\u00fcrttemberg, Theresia Bauer, die als &#8222;<em>unstreitig<\/em>&#8220; erkl\u00e4rt, dass man auf Experimente an Affen nicht verzichten kann.<\/h5>\n<p><span style=\"color: #ffffff;\"><strong><em>.<\/em><\/strong><\/span><\/p>\n<p><span style=\"color: #008080;\"><strong><em> <span style=\"color: #ffffff;\">.<\/span><\/em><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #008080;\"><strong><em>In Liebe und z\u00e4rtlichem Gedenken der vergessenen Tiere,<br \/>\nin Stehs\u00e4rgen ohne N\u00e4chte und Tage,<br \/>\nin den Forschungslaboratorien von Medizin und Wissenschaft,<br \/>\ndenn sie sind die Opfer eines endlosen, irren Verbrechens.<br \/>\n<\/em><\/strong><\/span><span style=\"color: #008080;\"><strong><em>(anonym)<\/em><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unsere Dienstaufsichtsbeschwerde \u00fcber Prof. Hans-Peter Thier\u00a0 wegen Verdacht auf illegale Versuche mit Primaten liegt jetzt auf dem Tisch des Rektors der Universit\u00e4t T\u00fcbingen, Prof. Bernd Engler, nach einer Wanderung seit der 15. April 2017 \u00fcber verschiedene involvierte Verwaltungsstellen \u00a0bei dieser extrem verstrickten und intransparenten Forschung (Hertie Stiftung,\u00a0 Regierungspr\u00e4sidium Darmstadt, Wissenschaftsministerium Baden-W\u00fcrttemberg), die sich alle als [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[9],"tags":[1273,1258,1267,185],"class_list":["post-7107","post","type-post","status-publish","format-standard","hentry","category-tierversuche-abschaffen","tag-bernd-engler","tag-hans-peter-thier","tag-stefan-treue","tag-wolf-singer"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts\/7107"}],"collection":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/comments?post=7107"}],"version-history":[{"count":0,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts\/7107\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/media?parent=7107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/categories?post=7107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/tags?post=7107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}