{"id":6648,"date":"2015-07-12T15:20:46","date_gmt":"2015-07-12T14:20:46","guid":{"rendered":"https:\/\/www.jocelyne-lopez.de\/blog\/?p=6648"},"modified":"2016-08-21T07:22:15","modified_gmt":"2016-08-21T06:22:15","slug":"verfassungsbeschwerde-wegen-der-tierhaltung-im-affenlabor-covance","status":"publish","type":"post","link":"https:\/\/www.jocelyne-lopez.de\/blog\/2015\/07\/verfassungsbeschwerde-wegen-der-tierhaltung-im-affenlabor-covance\/","title":{"rendered":"Verfassungsbeschwerde wegen der Tierhaltung im Affenlabor Covance"},"content":{"rendered":"<p style=\"text-align: justify;\">Eine Verfassungsbeschwerde wegen der Tierhaltung im Affenlabor Covance wurde von drei Tiersch\u00fctzerinnen und Tierrechtlerinnen als Privatpersonen eingeleitet (alphabetisch: Jocelyne Lopez, Sandra L\u00fcck und Gisela Urban):<\/p>\n<p style=\"text-align: center;\">.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.jocelyne-lopez.de\/blog\/wp-content\/uploads\/2015\/06\/Jo-Sandra-Gisela-Anti-Pelz-Demo-Duedo-2015.jpg\" alt=\"\" width=\"420\" height=\"276\" \/><\/p>\n<h5 style=\"text-align: center;\"><em>Jocelyne Lopez, Sandra L\u00fcck, Gisela Urban<\/em><br \/>\n<em>\u00a9 Copyright Jocelyne Lopez, 2015<br \/>\n<span style=\"color: #ffffff;\">.<\/span><\/em><\/h5>\n<p style=\"text-align: justify;\">Seit mehr als 10 Jahren, seitdem 2003 die Undercover-Recherchen vom ZDF-Journalisten Friedrich M\u00fclln durch TV-Sendungen ein Millionenpublikum in Deutschland und in der Schweiz unter Schock versetzt haben, konnte nichts helfen, um die barbarischen Zust\u00e4nde in diesem Labor ein Ende zu setzen: Weder die Welle der Emp\u00f6rung, der Trauer, des Entsetzens und der Besch\u00e4mung in der \u00d6ffentlichkeit, noch unz\u00e4hlige Protestaktionen und Demos, noch Ansprachen und Petitionen an die Politiker konnten irgendeine kleine \u00c4nderung bewirken, nichts, absolut nichts.<\/p>\n<p style=\"text-align: justify;\">Eine einmalige Vorgehensweise haben wir dann geplant und Schritt f\u00fcr Schritt zielstrebig verfolgt: <strong>Wir wenden uns an die Verfassungsrichter<\/strong>, die die Verst\u00f6\u00dfe gegen das Tierschutzgesetz und gegen die Grundrechte der Tiere und der B\u00fcrger feststellen, sowie die Bestimmungen des bestehenden Tierschutzgesetzes umsetzen lassen sollen.<\/p>\n<p style=\"text-align: justify;\">Um den Weg zum Bundesverfassungsgericht frei zu machen, mussten wir jedoch nachweisen, dass wir alle m\u00f6glichen Rechtsmittel zur Wiederherstellung der Rechtskonformit\u00e4t vorher ausgesch\u00f6pft haben \u2013 sonst ist eine Verfassungs-beschwerde nicht zul\u00e4ssig.<\/p>\n<p style=\"text-align: justify;\">Das haben wir auch konsequent getan und konnten die Linie halten:<br \/>\n<span style=\"color: #ffffff;\">.<\/span><\/p>\n<ol>\n<li style=\"text-align: justify;\">Wir haben Strafanzeige bei der Staatsanwaltschaft Bochum gegen die genehmigende Beh\u00f6rde LANUV NRW wegen Tierqu\u00e4lerei (Verst\u00f6\u00dfe gegen TierSchG \u00a7 1, 2, 7, 8 und 11) bei der Genehmigung der Versuche im Affenlabor Covance erstattet.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><\/li>\n<li style=\"text-align: justify;\">Da die Staatsanwaltschaft unsere Strafanzeige willk\u00fcrlich eingestellt hat, mit der unhaltbaren Begr\u00fcndung, dass kein Anfangsverdacht f\u00fcr eine verfolgbare Straftat vorl\u00e4ge, haben wir ein Klageerzwingungsverfahren beim Oberlandesgericht Hamm \u00fcber unseren sehr kompetenten und engagierten <a href=\"http:\/\/www.sanker-office.eu\/\" target=\"_blank\">Rechtsanwalt David Sanker<\/a>\u00a0 eingeleitet. Dies sollte bewirken, dass das Gericht die Staatsanwaltschaft zwingt, Ermittlungen einzuleiten und bei Best\u00e4tigung des Verdachts auf Tierqu\u00e4lerei die \u00f6ffentliche Klage im Interesse der Allgemeinheit zu erheben, d.h. die Beh\u00f6rde vor Gericht zur Verantwortung zu stellen.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><\/li>\n<li style=\"text-align: justify;\">Das Oberlandesgericht Hamm hat jedoch den formalen Standpunkt angef\u00fchrt, dass mangels an Verletzteneigenschaft nach \u00a7 172 StPO der Antrag zum Klageerzwingungsverfahren unzul\u00e4ssig sei.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\nDie \u201eVerletzteneigenschaft\u201c bedeutet, dass ein Kl\u00e4ger durch eine Straftat <strong>pers\u00f6nlich verletzt<\/strong> sein muss, was im Falle von Tierqu\u00e4lereien den B\u00fcrgern leider nicht anerkannt wird. Nicht einmal der Halter eines Tiers hat einen Anspruch darauf, Tierqu\u00e4lerei strafrechtlich verfolgen zu lassen! Da unser Rechtsanwalt in der Antragsschrift auf das Verfassungsgericht verwiesen hat, welche Ausnahmen im Grundgesetz und welche Pr\u00e4zedenzf\u00e4lle zur \u00dcberwindung der Verletzteneigenschaft vorliegen, ist es nur folgerichtig, dass wir das Verfassungsgericht jetzt mit einer Verfassungsbeschwerde bem\u00fcht haben. Das Oberlandesgericht Hamm hat uns hier de facto den Weg zum Verfassungsgericht frei gemacht und \u00fcberlassen.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Wir k\u00f6nnten also jetzt auf der Ebene der Verfassung etwas Grunds\u00e4tzliches erreichen, sowohl zur Durchsetzung der Rechte der Tiere, als auch der Rechte der B\u00fcrger in einem Rechtsstaat: <strong>Jeder einzelne B\u00fcrger als Privatperson<\/strong> h\u00e4tte bei gravierenden strafrechtlichen Handlungen einer Beh\u00f6rde einen Anspruch darauf, \u00fcber die Strafverfolgung und die Erhebung der \u00f6ffentlichen Klage durch die Staatsanwaltschaften sie vor Gericht zu stellen. Dies ist von grunds\u00e4tzlicher Bedeutung und w\u00fcrde die juristische Landschaft im Bereich des Tierschutzes ma\u00dfgeblich ver\u00e4ndern, sowie der Rechtsfortbildung dienen.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><strong>Wir sind zuversichtlich und vertrauen den Verfassungsrichtern zum Schutz der Grundrechte der Tiere und der B\u00fcrger auf dem Grundsatz des Justizgew\u00e4hrungsanspruches!<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.jocelyne-lopez.de\/blog\/wp-content\/uploads\/2015\/03\/Covance-Banner.jpg\" alt=\"\" width=\"500\" height=\"262\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: center;\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<br \/>\n<strong>Neue Entwicklung &#8211; 20.08.2016<br \/>\n<\/strong><\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.jocelyne-lopez.de\/blog\/2016\/08\/verfassungsbeschwerde-wegen-affenlabor-covance-nicht-zugelassen-wir-gehen-in-die-europaeische-instanz\/\">Verfassungsbeschwerde wegen Affenlabor COVANCE nicht zugelassen:<br \/>\nWir gehen in die europ\u00e4ische Instanz!<\/a><\/strong><br \/>\n<span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: center;\">\n","protected":false},"excerpt":{"rendered":"<p>Eine Verfassungsbeschwerde wegen der Tierhaltung im Affenlabor Covance wurde von drei Tiersch\u00fctzerinnen und Tierrechtlerinnen als Privatpersonen eingeleitet (alphabetisch: Jocelyne Lopez, Sandra L\u00fcck und Gisela Urban): . Jocelyne Lopez, Sandra L\u00fcck, Gisela Urban \u00a9 Copyright Jocelyne Lopez, 2015 . Seit mehr als 10 Jahren, seitdem 2003 die Undercover-Recherchen vom ZDF-Journalisten Friedrich M\u00fclln durch TV-Sendungen ein Millionenpublikum [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[9],"tags":[830,311,1239,128],"class_list":["post-6648","post","type-post","status-publish","format-standard","hentry","category-tierversuche-abschaffen","tag-affenversuche","tag-covance","tag-david-sanker","tag-verfassungsbeschwerde"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts\/6648"}],"collection":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/comments?post=6648"}],"version-history":[{"count":0,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts\/6648\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/media?parent=6648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/categories?post=6648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/tags?post=6648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}