{"id":5659,"date":"2014-01-09T07:37:58","date_gmt":"2014-01-09T06:37:58","guid":{"rendered":"https:\/\/www.jocelyne-lopez.de\/blog\/?p=5659"},"modified":"2014-06-08T07:54:34","modified_gmt":"2014-06-08T06:54:34","slug":"ablehnung-der-petition-beim-landtag-nrw-wegen-verstoessen-gegen-das-tierschutzgesetz-durch-lanuv-nrw-kann-die-gruene-fraktion-helfen","status":"publish","type":"post","link":"https:\/\/www.jocelyne-lopez.de\/blog\/2014\/01\/ablehnung-der-petition-beim-landtag-nrw-wegen-verstoessen-gegen-das-tierschutzgesetz-durch-lanuv-nrw-kann-die-gruene-fraktion-helfen\/","title":{"rendered":"Ablehnung der Petition beim Landtag NRW wegen Verst\u00f6\u00dfen gegen das Tierschutzgesetz durch LANUV NRW: Kann die GR\u00dcNE-Fraktion helfen?"},"content":{"rendered":"<p>Wie es in meinem Blog-Artikel <a href=\"https:\/\/www.jocelyne-lopez.de\/blog\/2013\/12\/landtag-nrw-wie-die-verfassung-zur-farce-verwandelt-wird\/\" target=\"_blank\">Landtag NRW: Wie die Verfassung zur Farce verwandelt wird<\/a> dargelegt wurde, k\u00f6nnen wir den skandal\u00f6sen Beschlu\u00df des Landtags NRW nicht einfach hinnehmen, die langj\u00e4hrigen Verst\u00f6\u00dfe gegen das Tierschutzgesetz \u00a7\u00a7 7 und 8 durch LANUV NRW bei der Genehmigung der Primatenversuche in der Hirnforschung an der Ruhr-Universit\u00e4t Bochum ungeahndet zu lassen.<\/p>\n<p>Es ist f\u00fcr Au\u00dfenseiter aufgrund der Stellungnahme des Petitionsausschu\u00dfes vom 20.12.13 sehr daran zu zweifeln, dass ein Fachausschu\u00df \u201eTierschutz\u201c bei der Bearbeitung der Petition berufen wurde, da auf keinen einzigen von unserer drei Vorw\u00fcrfe des Versto\u00dfes gegen das Tierschutzgesetz eingegangen wurde: lediglich die haltlose Argumentation der Staatsanwaltschaft wurde wortreich wiedergegeben, dass unsere Vorw\u00fcrfe nur auf \u201e<em>Vermutungen<\/em>\u201c beruhen sollen. Es ist auf gar keinen Fall eine sachgerechte und annehmbare Bearbeitung des Sachverhalts!<\/p>\n<p>Wir sehen dementsprechend das Petitionsverfahren nicht als abgeschlossen an und pr\u00fcfen derzeit die politisch-rechtlichen M\u00f6glichkeiten, diesen hochbedenklichen Beschlu\u00df im Interesse der Allgemeinheit r\u00fcckg\u00e4ngig zu machen.<\/p>\n<p>Wir haben schon jetzt die GR\u00dcNE-Fraktion angesprochen und um Hilfe gebeten:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" alt=\"\" src=\"http:\/\/www.landtag.nrw.de\/portal\/Grafiken\/Fotos\/Abgeordnete\/klein_16WP\/priggen.jpg\" width=\"115\" height=\"160\" \/><\/p>\n<p class=\"MsoNormal\"><a href=\"http:\/\/www.landtag.nrw.de\/portal\/WWW\/Webmaster\/GB_I\/I.1\/Abgeordnete\/abgeordnetendetail.jsp?k=01418\" target=\"_blank\">Abgeordneter Reiner Priggen<\/a><br \/>\nVorsitzender der GR\u00dcNE-Fraktion<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>Kann die GR\u00dcNE-Fraktion helfen, die Rechte der Tiere und der B\u00fcrger im Land Nordrhein-Westfalen zu garantieren und zu sch\u00fctzen? Es darf in unserem Rechtsstaat nicht hingenommen werden, dass die Staatanwaltschaft aus Willk\u00fcr oder Fahrl\u00e4ssigkeit den Weg zu einer gerichtlichen Pr\u00fcfung bei offensichtlichen Gesetzverst\u00f6\u00dfen einer Beh\u00f6rde versperrt. LANUV NRW muss sich vor Gericht wegen gesetzwidrigem Verhalten verantworten! Das ist das legitimierte Recht der Tiere und der B\u00fcrger. Wir sind entschlossen, dieses Recht wenn n\u00f6tig bis zum Europ\u00e4ischen Gerichtshof zu verteidigen.<\/p>\n<p class=\"MsoNormal\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p class=\"MsoNormal\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<br \/>\nSiehe auch:<\/p>\n<p><a href=\"https:\/\/www.jocelyne-lopez.de\/blog\/2014\/02\/das-verwaltungsgericht-duesseldorf-hebelt-das-informationsfreiheitsgesetz-aus\/\" target=\"_blank\">Verwaltungsgericht D\u00fcsseldorf hebelt das Informationsfreiheitsgesetz aus<\/a><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie es in meinem Blog-Artikel Landtag NRW: Wie die Verfassung zur Farce verwandelt wird dargelegt wurde, k\u00f6nnen wir den skandal\u00f6sen Beschlu\u00df des Landtags NRW nicht einfach hinnehmen, die langj\u00e4hrigen Verst\u00f6\u00dfe gegen das Tierschutzgesetz \u00a7\u00a7 7 und 8 durch LANUV NRW bei der Genehmigung der Primatenversuche in der Hirnforschung an der Ruhr-Universit\u00e4t Bochum ungeahndet zu lassen. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[9],"tags":[830,1001,869,769,831,1009,885,894,8,7,1334],"class_list":["post-5659","post","type-post","status-publish","format-standard","hentry","category-tierversuche-abschaffen","tag-affenversuche","tag-landtag-nrw","tag-lanuv-nrw","tag-max-planck-insitut-fur-hirnforschung","tag-primatenversuche","tag-reiner-priggen","tag-rub","tag-ruhruniversitat-bochum","tag-tierrechte","tag-tierschutz","tag-tierversuche-abschaffen"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts\/5659"}],"collection":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/comments?post=5659"}],"version-history":[{"count":0,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts\/5659\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/media?parent=5659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/categories?post=5659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/tags?post=5659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}