{"id":5555,"date":"2013-10-09T06:06:10","date_gmt":"2013-10-09T05:06:10","guid":{"rendered":"https:\/\/www.jocelyne-lopez.de\/blog\/?p=5555"},"modified":"2013-10-09T06:06:10","modified_gmt":"2013-10-09T05:06:10","slug":"cern-neutrinoexperiment-die-ptb-soll-sich-etwas-besseres-zur-vernebelung-einfallen-lassen","status":"publish","type":"post","link":"https:\/\/www.jocelyne-lopez.de\/blog\/2013\/10\/cern-neutrinoexperiment-die-ptb-soll-sich-etwas-besseres-zur-vernebelung-einfallen-lassen\/","title":{"rendered":"CERN Neutrinoexperiment: Die PTB soll sich etwas Besseres zur Vernebelung einfallen lassen"},"content":{"rendered":"<p>Ich komme auf meinen Blog-Eintrag <a href=\"https:\/\/www.jocelyne-lopez.de\/blog\/2013\/10\/die-mathematik-der-relativitatstheorie-ist-schrott\/\" target=\"_blank\">Die Mathematik der Relativit\u00e4tstheorie ist Schrott <\/a>zur\u00fcck und gebe einen weiteren Beitrag von mir vom 07.10.2013 im MAHAG-Forum in diesem Zusammenhang wieder:<\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><a href=\"http:\/\/www.mahag.com\/neufor\/viewtopic.php?f=6&amp;t=472&amp;start=780#p63071\" target=\"_blank\">06.10.2013 \u2013 Zitat von Jocelyne Lopez<\/a>:<\/p>\n<p>Nat\u00fcrlich kommt immer bei der Ausrechnung der Lorentztransformation der Wert f\u00fcr c raus, den man vorausgesetzt bzw. festgesetzt hat. Es kommt immer das gleiche raus: c=c, egal welchen Wert man f\u00fcr c oder f\u00fcr v ansetzt. Einfacher geht\u2019s nicht. Daf\u00fcr brauche ich nicht einmal eine Ausrechnung, ich kann das sogar blitzschnell im Kopf rechnen, so begabt bin ich in Mathe, wer h\u00e4tte das gedacht? ;- ) Ich brauche sogar nicht einmal eine Formel daf\u00fcr: Man h\u00e4tte anstatt die Lorentztransformation zu tradieren ruhig in Prosa lehren k\u00f6nnen: \u201c<i>Der angesetzte Wert von c ver\u00e4ndert sich nie, fertig<\/i>\u201c, und gut w\u00e4r\u2019s gewesen.<\/p>\n<p>Das gleiche gilt nat\u00fcrlich f\u00fcr die sogenannte relativistische Geschwindigkeitsaddition, die mit einfacher Algebra zu l\u00f6sen ist (Einstein betonte auch, dass die Mathematik seiner Theorie von Abiturienten zug\u00e4nglich sei):<\/p>\n<p style=\"padding-left: 30px;\">(c + v) \/ (1 + c*v\/c\u00b2) = c<br \/>\n1 \/ (1 + c (1-c)\/c\u00b2) = c<br \/>\n1 \/ (1 + (1-c)\/c = c<br \/>\n1 \/ (1 \u2013 1\/c \u2013 1) = c<br \/>\n1 \/ (1\/c) = c<br \/>\nc = c<\/p>\n<p>Auch nur mit Algebra kommt heraus, dass v=0 immer rauskommt, egal welchen Wert man daf\u00fcr ansetzt, also dass die Geschwindigkeit des Beobachters rein mathematisch aus der Natur weggezaubert wird. Praktisch. Als ob die Natur sich jederzeit an unsere Voraussetzungen und Dekrete halten w\u00fcrde, was f\u00fcr einen Schwachsinn.\u00a0\u00a0<\/p>\n<p>Egal welchen Wert man f\u00fcr c ansetzt, kommt dieser Wert immer am Ende der Ausrechnung raus, totsicher, man darf sich jegliche Ausrechnung sparen. Ekkehard Friebe hat mir vor fast 10 Jahren den Wert f\u00fcr c rausgesucht, der zur Lebzeit Einsteins galt und zum Beispiel Maxwell 1865 f\u00fcr seine Gleichungen angesetzt hatte:\u00a0<\/p>\n<p style=\"padding-left: 30px;\">MM. WEBER and KOHLRAUSCH: v = 310,740,000 Meter pro Sekunde<br \/>\nM. FIZEAU: V = 314,858,000 Meter pro Sekunde<br \/>\nM. FOUCAULT: V = 298,000,000 Meter pro Sekunde<br \/>\nAbgeleitet vom Koeffizienten der Aberration: V = 308,000,000 Meter pro Sekunde.<\/p>\n<p>Die Mathematik der Speziellen Relativit\u00e4tstheorie ist Schrott.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.mahag.com\/neufor\/viewtopic.php?f=6&amp;t=472&amp;p=63111#p63111\" target=\"_blank\">07.10.2013 \u2013 Zitat von Jocelyne Lopez<\/a>:<\/p>\n<p>Auf meine Frage, wieso das Ergebnis des CERN-Neutrinoexperiments offiziell als Best\u00e4tigung der Annahme Einsteins c=const erkl\u00e4rt wurde, obwohl man diese Annahme durch c+v \u201e<i>korrigiert<\/i>\u201c hat, antwortete die PTB:<\/p>\n<p style=\"padding-left: 30px;\"><b><a href=\"http:\/\/www.kritik-relativitaetstheorie.de\/2013\/03\/cern-neutrinoexperiment-die-ptb-lost-den-widerspruch-in-ihrer-interpretation-der-ergebnisse-nicht\/\" target=\"_blank\">22.3.2013 \u2013 Zitat PTB<\/a>:<\/b><\/p>\n<p style=\"padding-left: 30px;\">[&#8230;] <em>Ob man es mag oder nicht: Unabh\u00e4ngig davon, was in Blogs, Tweets oder sonstwo geschrieben wird, es gibt keinen einzigen experimentellen Beleg daf\u00fcr, dass irgendein Materieteilchen oder Information sich im Vakuum schneller als das Licht bewegt. Wenn man in diesem Feld, wo die Intuition versagt, genau verstehen will, was passiert (und was nicht passieren kann), reicht eine Argumentation in der Alltagssprache einfach nicht: Man muss sich des korrekten und vollst\u00e4ndigen mathematischen Formalismus bedienen. Das ist m\u00fchevoll, erfordert viele Vorkenntnisse und bietet viele M\u00f6glichkeiten, etwas falsch zu machen. Nicht ohne Grund lernen Physikstudenten diese Dinge erst in sp\u00e4teren Studienjahren.<\/em><\/p>\n<p style=\"padding-left: 30px;\"><em>Ein \u00fcblicher Fehler im Bereich der Relativit\u00e4tstheorie, der zu endlosen Diskussionen f\u00fchren kann, ist, dass man in einem Koordinatensystem (Bezugssystem) anf\u00e4ngt zu rechnen und zwischendurch, ohne es zu merken, in einem anderen System weiterrechnet.<\/em> [&#8230;]<\/p>\n<p>Daraus geht hervor, dass man bei der Auswertung der Messergebnisse den \u201e<i>korrekten und vollst\u00e4ndigen mathematischen Formalismus<\/i>\u201c der Speziellen Relativit\u00e4tstheorie angewandt hat, sprich die Lorentztransformation, die mit Einsatz von zwei Beobachter-Bezugssystemen arbeitet.<\/p>\n<p>Kann mir jemand erkl\u00e4ren, was ein zweites Beobachter-Bezugssystem bei diesem Experiment zu suchen hat, das eine Einwegmessung ist und folglich nur ein einziges Beobachter-Bezugssystem involviert (Labor in Gran Sasso)? Kann mir das jemand erkl\u00e4ren??<\/p>\n<p>Dann erkl\u00e4re ich es selbst: Die Anwendung des \u201e<i>korrekten und vollst\u00e4ndigen mathematischen Formalismus<\/i>\u201c der Speziellen Relativit\u00e4tstheorie, sprich die Lorentztransformation, darf die PTB ruhig einpacken und sich etwas Anderes als Vernebelung einfallen lassen.<\/p>\n<p>Bei dieser Einwegmessung kommt n\u00e4mlich nur eine Geschwindigkeitsaddition als mathematischer Formalismus in Betracht, und sonst nichts.<\/p>\n<p>Entweder verwendet man<\/p>\n<p style=\"padding-left: 30px;\">a) die klassische Geschwindigkeitsaddition nach Galilei c+\/-v (unbestimmt).<\/p>\n<p>oder<\/p>\n<p style=\"padding-left: 30px;\">b) die relativistische Geschwindigkeitsaddition c+v=c (bestimmt, siehe oben).<\/p>\n<p>Die relativistische Geschwindigkeitsaddition c+v=c ist jedoch in diesem Fall nicht anwendbar, weil v die Rotationsgeschwindigkeit der Erde ist und nicht 0 betr\u00e4gt. Es sei denn, der CERN hat w\u00e4hrend des Experiments die Erde kurz angehalten &#8211; m\u00f6glich ist alles mit der Relativit\u00e4tstheorie, wenn man es gerade braucht.\u00a0<\/p>\n<p>&nbsp;<\/p>\n<p>\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014-<br \/>\nSiehe auch in diesem Zusammenhang:<\/p>\n<p><a title=\"Permanent Link to CERN-Neutrinoexperiment: Petition beim Deutschen Bundestag vom 11.08.2013\" href=\"http:\/\/www.kritik-relativitaetstheorie.de\/2013\/08\/cern-neutrinoexperiment-petition-beim-deutschen-bundestag-vom-11-08-2013\/\" target=\"_blank\">CERN-Neutrinoexperiment: Petition beim Deutschen Bundestag vom 11.08.2013<\/a><\/p>\n<p><a title=\"Permanent Link to CERN-Experiment: Die Petition vom 11.08.13 beim Bundestag wird nicht ver\u00f6ffentlicht\" href=\"http:\/\/www.kritik-relativitaetstheorie.de\/2013\/08\/cern-experiment-die-petition-vom-11-08-13-beim-bundestag-wird-nicht-veroffentlicht\/\" target=\"_blank\">CERN-Experiment: Die Petition vom 11.08.13 beim Bundestag wird nicht ver\u00f6ffentlicht<\/a>\u00a0(angeblich aus Mangel an \u00f6ffentliches Interesse)<\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich komme auf meinen Blog-Eintrag Die Mathematik der Relativit\u00e4tstheorie ist Schrott zur\u00fcck und gebe einen weiteren Beitrag von mir vom 07.10.2013 im MAHAG-Forum in diesem Zusammenhang wieder: . 06.10.2013 \u2013 Zitat von Jocelyne Lopez: Nat\u00fcrlich kommt immer bei der Ausrechnung der Lorentztransformation der Wert f\u00fcr c raus, den man vorausgesetzt bzw. festgesetzt hat. Es kommt [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[13],"tags":[944,896,33,1335,16,270,1336,893,839],"class_list":["post-5555","post","type-post","status-publish","format-standard","hentry","category-kritik-der-relativitatstheorie","tag-cern-experiment","tag-cern-neutrinoexperiment","tag-ekkehard-friebe","tag-go-mueller","tag-gom-projekt","tag-jocelyne-lopez","tag-kritik-der-relativitatstheorie","tag-physikalisch-technische-bundesanstalt","tag-ptb"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts\/5555"}],"collection":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/comments?post=5555"}],"version-history":[{"count":0,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts\/5555\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/media?parent=5555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/categories?post=5555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/tags?post=5555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}