{"id":5224,"date":"2012-09-10T05:41:25","date_gmt":"2012-09-10T04:41:25","guid":{"rendered":"https:\/\/www.jocelyne-lopez.de\/blog\/?p=5224"},"modified":"2012-09-10T05:41:25","modified_gmt":"2012-09-10T04:41:25","slug":"10-fragen-an-die-bundesministerin-fur-bildung-und-forschung-annette-schavan-uber-die-wissenschaftsfreiheit-nach-art-5-grundgesetz","status":"publish","type":"post","link":"https:\/\/www.jocelyne-lopez.de\/blog\/2012\/09\/10-fragen-an-die-bundesministerin-fur-bildung-und-forschung-annette-schavan-uber-die-wissenschaftsfreiheit-nach-art-5-grundgesetz\/","title":{"rendered":"10 Fragen an die Bundesministerin f\u00fcr Bildung und Forschung Annette Schavan \u00fcber die Wissenschaftsfreiheit nach Art. 5 Grundgesetz"},"content":{"rendered":"<p>Nachstehend Ausz\u00fcge aus dem\u00a0 Offenen Brief der Forschungsgruppe G.O. Mueller \u00fcber Wissenschaftsfreiheit nach GG Art. 5 an Frau Bundesministerin Annette Schavan vom 29.01.2006:<br \/>\n<span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>Sehr geehrte Frau Ministerin,<\/p>\n<p>[&#8230;]<\/p>\n<p>Wir bitten Sie h\u00f6flichst, unseren Arbeitsergebnissen, die wir seit Dezember 2001 kontinuierlich immer mehr Vertretern der \u00d6ffentlichkeit in Deutschland und jetzt auch in anderen L\u00e4ndern vorlegen, die Ehre einer Antwort zuteil werden zu lassen. Die Fragen unseres \u201c<em>Offenen Briefes<\/em>\u201d v. 28.10.05 lassen sich in wenigen Zeilen zusammenfassen und erm\u00f6glichen klare Antworten:<\/p>\n<p style=\"PADDING-LEFT: 30px\">1. Gibt es eine Tradition der Theoriekritik seit 95 Jahren? \u2013 Ja oder nein?<\/p>\n<p style=\"PADDING-LEFT: 30px\">2. Ist diese Theoriekritik seit 80 Jahren unterdr\u00fcckt und verleumdet worden? \u2013 Ja oder Nein?<\/p>\n<p style=\"PADDING-LEFT: 30px\">3. Ist diese Theoriekritik in der wissenschaftlichen Diskussion argumentativ ausger\u00e4umt worden? \u2013 Ja oder Nein?<\/p>\n<p style=\"PADDING-LEFT: 30px\">4. Kommen in der wissenschaftlichen Diskussion der theoretischen Physik zur Speziellen Relativit\u00e4tstheorie \u2013 wie in der Wissenschaft allgemein \u00fcblich \u2013 Minderheitsmeinungen fachlich und \u00f6ffentlich zur Sprache? \u2013 Ja oder Nein?<\/p>\n<p style=\"PADDING-LEFT: 30px\">5. Haben die Amtsinhaber der theoretischen Physik mit der Diskriminierung und dem Boykott von kritischen Minderheitsauffassungen durch deren Ausschlu\u00df aus der wissenschaftlichen Diskussion und damit den Ausschlu\u00df der Kritiker von den Grundrechten massenhaft ihre Amtseide auf das Grundgesetz gebrochen? \u2013 Ja oder Nein?<\/p>\n<p style=\"PADDING-LEFT: 30px\">6. Sind die Wissenschaftsredaktionen der deutschen Tagespresse, der Zeitschriften und der elektronischen Massenmedien zur Unterdr\u00fcckung der Theoriekritik erfolgreich gleichgeschaltet worden? \u2013 Ja oder Nein?<\/p>\n<p style=\"PADDING-LEFT: 30px\">7. Herrscht in allen Bereichen unserer Gesellschaft (mit der einzigen Ausnahme: Internet) \u2013 also in Universit\u00e4ten, Massenmedien, Schulen, allgemeinen und fachlichen Zeitschriften, Verlagsprogrammen \u2013 bez\u00fcglich dieser einen Theorie eine von dieser gesetzwidrigen Zensur verordnete Friedhofsruhe? \u2013 Ja oder nein?<\/p>\n<p style=\"PADDING-LEFT: 30px\">8. Wird schon in den Schulen von den Fachlehrern mit p\u00e4dagogischem Notendruck ein gegebenenfalls auch heuchlerisches Bekenntnis der Sch\u00fcler zur Theorie verlangt und durchgesetzt, weil jeder, der kritisiert. f\u00fcr dumm erkl\u00e4rt wird? \u2013 Ja oder Nein?<\/p>\n<p style=\"PADDING-LEFT: 30px\">9. Werden Zweifel der Sch\u00fcler von vornherein abgekanzelt und damit bei den Sch\u00fclern (und \u00fcbrigens auch bei den Lehrerkollegen der anderen F\u00e4cher) Duckm\u00e4usertum und Opportunismus gez\u00fcchtet? \u2013 Ja oder Nein?<\/p>\n<p style=\"PADDING-LEFT: 30px\">10. Wird die \u00d6ffentlichkeit durch das jahrzehntelange Verschweigen der Existenz einer kritischen Tradition betrogen? \u2013 Ja oder Nein?<\/p>\n<p>Wir beantworten die Fragen 3 und 4 mit \u201c<em>Nein<\/em>\u201c, alle anderen Fragen mit \u201c<em>Ja<\/em>\u201c. Wir glauben, da\u00df die Beweise f\u00fcr unsere Beantwortungen mit etwas Arbeitsaufwand, aber mit gro\u00dfer Sicherheit zu liefern sind, weil mit unserer Dokumentation das wichtigste Material bereitliegt.<\/p>\n<p>Von einer Bundesministerin, die mit ihrem Ministerium einen ausreichenden Apparat zu ihrer Verf\u00fcgung hat, sollten Bundesb\u00fcrger in ihrem Kampf um ein Grundrecht zumindest eine klare Antwort erwarten d\u00fcrfen, damit sie ihre weiteren Schritte vern\u00fcnftig planen k\u00f6nnen. Wir haben vorstehend die 10 wichtigsten Fragen formuliert. Nun kann sie auch beim besten Willen niemand mehr \u00fcberlesen oder ignorieren.<\/p>\n<p>[&#8230;]\u00a0<\/p>\n<p><a href=\"http:\/\/www.ekkehard-friebe.de\/060921gom_schavan.pdf\" target=\"_blank\">den ganzen Brief lesen&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nachstehend Ausz\u00fcge aus dem\u00a0 Offenen Brief der Forschungsgruppe G.O. Mueller \u00fcber Wissenschaftsfreiheit nach GG Art. 5 an Frau Bundesministerin Annette Schavan vom 29.01.2006: . Sehr geehrte Frau Ministerin, [&#8230;] Wir bitten Sie h\u00f6flichst, unseren Arbeitsergebnissen, die wir seit Dezember 2001 kontinuierlich immer mehr Vertretern der \u00d6ffentlichkeit in Deutschland und jetzt auch in anderen L\u00e4ndern vorlegen, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[11,13],"tags":[119,33,1335,16,270,1336],"class_list":["post-5224","post","type-post","status-publish","format-standard","hentry","category-go-mueller","category-kritik-der-relativitatstheorie","tag-annette-schavan","tag-ekkehard-friebe","tag-go-mueller","tag-gom-projekt","tag-jocelyne-lopez","tag-kritik-der-relativitatstheorie"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts\/5224"}],"collection":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/comments?post=5224"}],"version-history":[{"count":0,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts\/5224\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/media?parent=5224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/categories?post=5224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/tags?post=5224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}