{"id":5097,"date":"2012-02-22T08:04:34","date_gmt":"2012-02-22T07:04:34","guid":{"rendered":"https:\/\/www.jocelyne-lopez.de\/blog\/?p=5097"},"modified":"2012-06-22T17:38:30","modified_gmt":"2012-06-22T16:38:30","slug":"staatstheorie-relativitatstheorie-wer-am-brunnen-sitzt-hat-nie-durst","status":"publish","type":"post","link":"https:\/\/www.jocelyne-lopez.de\/blog\/2012\/02\/staatstheorie-relativitatstheorie-wer-am-brunnen-sitzt-hat-nie-durst\/","title":{"rendered":"Staatstheorie Relativit\u00e4tstheorie: Wer am Brunnen sitzt hat nie Durst"},"content":{"rendered":"<p>Ich verweise auf meine <a rel=\"bookmark\" href=\"https:\/\/www.jocelyne-lopez.de\/blog\/2012\/02\/anfrage-an-frau-annette-schavan-wegen-vermittlung-der-kritik-der-relativitatstheorie-im-offentlichen-bildungssystem\/\" target=\"_blank\">Anfrage an Frau Annette Schavan wegen Vermittlung der Kritik der Relativit\u00e4tstheorie im \u00f6ffentlichen Bildungssystem <\/a>und gebe einige Austausche aus einer Diskussion im MAHAG-Forum wieder:<\/p>\n<p>\u00a0<\/p>\n<p><a href=\"http:\/\/www.mahag.com\/neufor\/viewtopic.php?f=6&amp;t=415&amp;start=40#p38128\" target=\"_blank\">21.02.12 \u2013 Zitat von Ernst<\/a>:<\/p>\n<p>Was ist eigentlich deine pers\u00f6nliche Motivation f\u00fcr diesen Aktionismus?<br \/>\nInwiefern bist Du betroffen?<br \/>\nWer ist \u00fcberhaupt betroffen?<br \/>\nGibt es keine wichtigeren und sinnvolleren Dinge in dieser unvollkommenen Gesellschaft, um sich zu engagieren?<\/p>\n<p>\u00a0<\/p>\n<p><a href=\"http:\/\/www.mahag.com\/neufor\/viewtopic.php?f=6&amp;t=415&amp;start=50#p38132\" target=\"_blank\">21.02.12 \u2013 Zitat von Jocelyne Lopez<\/a>:<\/p>\n<p>Es ist ein Anliegen der Allgemeinheit: Es geht um Verst\u00f6\u00dfe gegen das Grundgesetz.<br \/>\nLies bitte meine Beanstandungen im Text meiner E-Mail an die Ministerin Schavan, die ich so sachlich und pr\u00e4gnant wie m\u00f6glich zusammengestellt habe:<\/p>\n<p style=\"PADDING-LEFT: 60px\"><strong>Zitat Jocelyne Lopez:<br \/>\n<\/strong>Demnach ist hier zu beanstanden, dass die im \u00f6ffentlichen Bildungssystem offiziell zugelassenen Unterrichtsquellen Irref\u00fchrung der Sch\u00fcler und Studenten betreiben, dass Tausende von kritischen Autoren gegen\u00fcber den Studierenden disqualifiziert, zensiert und verleumdet werden, dass die Kritik einer Theorie aus dem \u00f6ffentlichen Unterricht aufgrund von Geschichtsf\u00e4lschung und von Verleumdungen v\u00f6llig ausgeblendet wird, dass die fachliche Kritik einer Theorie im Unterricht nicht vermittelt und behandelt wird und nur im Internet durch private Initiativen zur Verf\u00fcgung der Sch\u00fcler und Studenten steht, dass die Gebote der Nicht-Identifikation mit einer Theorie und der meinungsneutralen Wissenschaftspflege, die dem Staat per Grundgesetz Art. 5 \u00a7 3 vorgeschrieben werden, im \u00f6ffentlichen Bildungssystem missachtet werden. Das sind gravierende Verst\u00f6\u00dfe gegen das Grundgesetz.<\/p>\n<p>Diese Missst\u00e4nde betreffen ein paar Millionen Menschen allein in Deutschland: Sch\u00fcler, Studenten, Eltern, Steuerzahler, naturwissenschaftlich interessierte B\u00fcrger, gesellschaftlich-politisch interessierte B\u00fcrger, Politiker, Kritiker der Relativit\u00e4tstheorie, Lehrer, Lehrbeauftragte, Forscher, Historiker, Juristen, Journalisten usw. usw.<br \/>\nIn irgendeiner oder mehreren von diesen Personengruppen geh\u00f6re ich auch pers\u00f6nlich.<\/p>\n<p>\u00a0<\/p>\n<p><a href=\"http:\/\/www.mahag.com\/neufor\/viewtopic.php?f=6&amp;t=415&amp;start=50#p38134\" target=\"_blank\">21.02.12 \u2013 Zitat von Ernst<\/a>:<\/p>\n<p>Das ganze ist die Inszenierung einer Verschw\u00f6rungstheorie. Wonach die etablierten Physiker sich mit dem Staat verschworen haben, die Spezielle Relativit\u00e4tstheorie gegen jede Kritik abzuschirmen. Und entsprechend diesem Verschw\u00f6rungswahn werden dann auch Gegenverschw\u00f6rungsmethoden verwendet. Da wird ein geheimnisvoller G.O. M\u00fcller kreiert, der die F\u00e4den der Gegenverschw\u00f6rung zieht. Damit wird die Kritik zu einer unabsehbaren geheimen Macht aufgepusht. Mit dieser Assoziation mu\u00df doch ein gro\u00dfes Potential der Gegenverschw\u00f6rung existieren. Vor dem sich Staat und Gesellschaft in Acht nehmen m\u00fcssen. Dieser unbekannte Aufkl\u00e4rer hat die Macht, erbarmunslos zu agieren, sollte die Spezielle Relativit\u00e4tstheorie\u00a0von den Verschw\u00f6rern nicht entsorgt werden.<\/p>\n<p>Verschw\u00f6rungstheorien sind irrational. Ihre Apologeten auch. Dennoch werden die seltsamsten Verschw\u00f6rungen von &#8222;wachsamen&#8220; Beobachtern &#8222;aufgedeckt&#8220;. Diese hier ist besonders komisch.<\/p>\n<p>\u00a0<\/p>\n<p><a href=\"http:\/\/www.mahag.com\/neufor\/viewtopic.php?f=6&amp;t=415&amp;start=60#p38141\" target=\"_blank\">21.02.12 \u2013 Zitat von Jocelyne Lopez<\/a>:\n<\/p>\n<p style=\"PADDING-LEFT: 60px\"><em>Zitat von Ernst :<\/em> &#8222;Wonach die etablierten Physiker sich mit dem Staat verschworen haben, die Spezielle Relativit\u00e4tstheorie gegen jede Kritik abzuschirmen.&#8220;<\/p>\n<p>Die Bundesministerin Schavan wei\u00df mit hoher Wahrscheinlichkeit nichts von dem Umfang und der Stichhaltigkeit der Kritik. Sie ist keine Physikerin, und sie muss es auch nicht wissen. Daf\u00fcr hat sie ihre Beraterteam bzw. ihre Beh\u00f6rden. Aber die Beh\u00f6rde versto\u00dfen auch am laufenden Band gegen die Gesetze, das ist Gang und Gebe, die Verwaltungsgerichte k\u00f6nnen ein Lied davon singen. Sie versto\u00dfen gegen Gesetze aus Unwissen, aus Schlamperei und wohl auch in einzelnen F\u00e4llen aus Machenschaften, Seilschaften und Korruption. Wenn keiner nachfragt, l\u00e4uft es alles ungest\u00f6rt jahre- oder jahrzehntelang.<\/p>\n<p>Und es geht hier um Geld, um sehr viel Geld, es geht um einen riesigen Kuchen aus der Steuerkasse, der verteilt werden mu\u00df und ungl\u00fccklicherweise in der Wissenschaft ohne Aufsicht des Staates verteilt wird, anonym und ohne kontrolle: Siehe die umfangreiche Studie von zwei Juristen, die vor kurzem als einen ganzseitigen Artikel in der FAZ erschienen ist:<\/p>\n<p style=\"PADDING-LEFT: 60px\"><strong><a href=\"http:\/\/www.faz.net\/aktuell\/feuilleton\/forschung-und-lehre\/kritik-an-der-dfg-die-freie-wissenschaft-ist-bedroht-11497511.html\" target=\"_blank\">Die freie Wissenschaft ist bedroht<\/a><br \/>\nF\u00f6rdert die m\u00e4chtige Deutsche Forschungsgemeinschaft (DFG) den Ideenklau und die Selbstbedienung?<br \/>\nTransparenz ist f\u00fcr sie ein Fremdwort. Dieses Monopol ist bedenklich.<br \/>\nRoland Reu\u00df und Volker Rieble<\/strong>\n<\/p>\n<p style=\"PADDING-LEFT: 60px\">Ausz\u00fcge:<\/p>\n<p style=\"PADDING-LEFT: 60px\">[&#8230;] Die Deutsche Forschungsgemeinschaft ist ein Verein deutscher Universit\u00e4ten und Wissenschafts-organisationen (Forschungseinrichtungen, Akademien und wissenschaftliche Verb\u00e4nde). Ihr Zweck ist durch die Satzung bestimmt: Sie \u201edient der Wissenschaft in allen ihren Zweigen durch die finanzielle Unterst\u00fctzung von Forschungsaufgaben und durch die F\u00f6rderung der Zusammenarbeit unter den Forscherinnen und Forschern.\u201c Sie erh\u00e4lt Geld vom Staat, jedes Jahr etwa 2,5 Milliarden Euro. Dieses Geld verteilt sie an Forscher und Forschungseinrichtungen, vor allem f\u00fcr die F\u00f6rderung von Forschungsprojekten. Daneben nimmt sie mit Geld Einfluss auf die Forschungsstruktur, namentlich durch die von ihr verwaltete Exzellenzinitiative, die Spitzenuniversit\u00e4ten erhebliche Finanzmittel zuweist, aber ebenso durch die von der F\u00f6rderung abh\u00e4ngige Errichtung von Sonderforschungsbereichen.<br \/>\n[&#8230;]<br \/>\nDas sind Vorschl\u00e4ge, die wir diskutieren wollen. An der grunds\u00e4tzlichen Feststellung, dass die DFG als Organisation modernen Prinzipien guter Organisationsf\u00fchrung nicht entspricht, f\u00fchrt unseres Erachtens kein Weg vorbei. Es muss besser werden und damit anders \u2013 damit die DFG ihre Aufgabe k\u00fcnftig allein im Dienst der Wissenschaft versieht.<\/p>\n<p>Kein Wunder, dass auch Jahr f\u00fcr Jahr seit Jahrzehnten die etablierten Wissenschaften, einschlie\u00dflich der Physik nat\u00fcrlich, sich den Kuchen bequem unter den Nagel reissen k\u00f6nnen. &#8222;<em>Wer am Brunnen sitzt hat nie Durst<\/em>&#8220; sagt eine arabische Redewendung&#8230;<\/p>\n<p>Das ist keine &#8222;<em>Verschw\u00f6rung<\/em>&#8222;, das ist ganz banale Machenschaften &#8211; aus Geldgier, aus Prestigegier, aus Karrieresucht, aus Einflu\u00dfsucht. Ganz was Banales, nix mit &#8222;<em>Verschw\u00f6rungen<\/em>&#8222;.<\/p>\n<p>Auch Karl Popper hat uns mal als Insider einen Blick hinter die Kulissen der Wissenschat gew\u00e4hrt, siehe: <a href=\"http:\/\/www.kritik-relativitaetstheorie.de\/2011\/06\/die-physik-in-der-sackgasse\/\" target=\"_blank\">Die Physik in der Sackgasse?<\/a>\n<\/p>\n<p style=\"PADDING-LEFT: 60px\">Erinnern wir uns doch eines Interviews, welches Karl Popper (1902-1994) der Zeitung DIE WELT am 29. Januar 1990 gab (1991 ver\u00f6ffentlicht als Taschenbuch bei Ullstein unter dem Titel \u201dIch wei\u00df, da\u00df ich nichts wei\u00df \u2013 und kaum das\u201d):<\/p>\n<p style=\"PADDING-LEFT: 60px\"><strong>Popper<\/strong>: Wir Intellektuellen haben schauerliche Dinge gemacht, wir sind eine gro\u00dfe Gefahr. Wir bilden uns viel ein \u2013 wir wissen nicht, wie wenig wir wissen. Und wir Intellektuellen sind nicht nur anma\u00dfend, sondern auch bestechlich.<\/p>\n<p style=\"PADDING-LEFT: 60px\"><strong>WELT<\/strong>: Materiell bestechlich?<\/p>\n<p style=\"PADDING-LEFT: 60px\"><strong>Popper<\/strong>: Ich meine nicht nur mit Geld, sondern auch bestechlich durch Ansehen, Macht, Einflu\u00df und so weiter. Das ist leider so. Man m\u00fc\u00dfte auch hier eine neue Mode schaffen. Ich hoffe, da\u00df es f\u00fcr Intellektuelle einmal modern werden wird, bescheiden zu sein. Das ginge schon. Nat\u00fcrlich bin ich nicht der beste Mann, um eine neue Mode zu kreieren.<\/p>\n<p style=\"PADDING-LEFT: 60px\"><strong>WELT:<\/strong> Welchen \u201cModetrend\u201d erkennen Sie heute bei den Intellektuellen?<\/p>\n<p style=\"PADDING-LEFT: 60px\"><strong>Popper<\/strong>: Sie machen aus Theorien Ideologien. Selbst in der Physik und in der Biologie gibt es leider viele Ideologien. [&#8230;] \u00dcberall, auch in diesen Fachbereichen, gibt es einen Dogmatismus, gegen den es schwierig ist, sich durchzusetzen. [&#8230;]<br \/>\nIch bin ein begeisterter Anh\u00e4nger der Wissenschaft. Physik und Biologie sind f\u00fcr mich gro\u00dfartige Wissenschaften, und ich halte die meisten Physiker und Biologen f\u00fcr sehr gescheit und gewissenhaft. Aber: Sie stehen unter Druck. Diesen Druck gibt es erst seit dem zweiten Weltkrieg, seitdem so viel Geld f\u00fcr die Wissenschaft ausgegeben wird.<\/p>\n<p>Ja, es wird sehr viel Geld f\u00fcr die Wissenschaft ausgegeben, Steuergeld. Es geht nicht um \u201e<em>Verschw\u00f6rung<\/em>\u201c, es geht um Geld, um sehr viel Geld. Es geht wohl auch um Fehlleistungen eines fehlgeleiteten Systems, es geht wohl auch um Fehlleistung von einzelnen Mainstream Akteuren und Mainstream Seilschaften, die seit Jahrzehnten dicht an der Geldquelle sitzen. Nix mit \u201e<em>Verschw\u00f6rung<\/em>\u201c&#8230;<\/p>\n<p>Eine Forschungseinrichtung sitzt wohl auf jeden Fall dicht an der Steuergeld-Geldquelle: das Albert Einstein Institut, das mir auch 2007 von der Ministerin Schavan als zust\u00e4ndig f\u00fcr einen Meinungsstreit \u00fcber die Relativit\u00e4tstheorie genannt wurde &#8211; obwohl es sich dazu unf\u00e4hig erwiesen hat. Das kann man allein als Au\u00dfenstehender merken, es schwimmt wohl im Geld:<\/p>\n<ul>\n<li>Das Institut besch\u00e4ftigt insgesamt ca. 150 feste Mitarbeiter in Golm und Hannover<\/li>\n<li>Es betreibt einen Glanzpapier PR-Auftritt \u00a0in der \u00d6ffentlichkeit zur Marketing der Staatstheorie in den Massenmedien, sowohl f\u00fcr seine Forschungs- als auch f\u00fcr seine Lehrt\u00e4tigkeiten<\/li>\n<li>Es konnte locker vom Bund 10 Mio Euro Steuergeld f\u00fcr das Vermarkten der Staatstheorie allein im Einstein-Jahr 2005 lockermachen und sich dabei noch erlauben die Kritik der Relativit\u00e4tstheorie v\u00f6llig auszublenden und in den \u00a0Augen der \u00d6ffentlichkeit manipulativ herabzusetzen, siehe\u00a0<a href=\"http:\/\/www.kritik-relativitaetstheorie.de\/2011\/09\/bundesministerium-loscht-kritik-auf-der-%e2%80%9ceinsteinjahr%e2%80%9d-webseite\/\" target=\"_blank\">hier<\/a>,\u00a0<a href=\"http:\/\/www.kritik-relativitaetstheorie.de\/2011\/09\/das-max-planck-institut-fur-wissenschaftsgeschichte-und-geschichtsfalschung\/\" target=\"_blank\">hier<\/a>, und\u00a0<a href=\"http:\/\/www.kritik-relativitaetstheorie.de\/2008\/12\/10-millionen-euros-fur-das-feiern-einer-unsinnigen-theorie\/\" target=\"_blank\">hier<\/a>.\u00a0<\/li>\n<li>Es sorgt wohl ma\u00dfgeblich in alle Gremien daf\u00fcr, dass einzig relativit\u00e4tstheoriekonforme Forschungsauftr\u00e4ge erteilt werden und eine Chance auf Erfolg bei der Verteilung der \u00f6ffentlichen Forschungsgelder haben.<\/li>\n<\/ul>\n<p>Es ist nicht von schlechten Eltern Vertreter und Anh\u00e4nger der Staatstheorie zu sein, kann man wohl sagen&#8230; Wer am Brunnen sitzt hat nie Durst.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich verweise auf meine Anfrage an Frau Annette Schavan wegen Vermittlung der Kritik der Relativit\u00e4tstheorie im \u00f6ffentlichen Bildungssystem und gebe einige Austausche aus einer Diskussion im MAHAG-Forum wieder: \u00a0 21.02.12 \u2013 Zitat von Ernst: Was ist eigentlich deine pers\u00f6nliche Motivation f\u00fcr diesen Aktionismus? Inwiefern bist Du betroffen? Wer ist \u00fcberhaupt betroffen? Gibt es keine wichtigeren [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[13],"tags":[41,119,780],"class_list":["post-5097","post","type-post","status-publish","format-standard","hentry","category-kritik-der-relativitatstheorie","tag-albert-einstein-institut","tag-annette-schavan","tag-deutsche-forschungsgemeinschaft"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts\/5097"}],"collection":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/comments?post=5097"}],"version-history":[{"count":0,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts\/5097\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/media?parent=5097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/categories?post=5097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/tags?post=5097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}