{"id":5061,"date":"2012-01-01T08:52:11","date_gmt":"2012-01-01T07:52:11","guid":{"rendered":"https:\/\/www.jocelyne-lopez.de\/blog\/?p=5061"},"modified":"2012-01-01T08:52:11","modified_gmt":"2012-01-01T07:52:11","slug":"alle-aktivisten-werden-im-internet-gemobbt","status":"publish","type":"post","link":"https:\/\/www.jocelyne-lopez.de\/blog\/2012\/01\/alle-aktivisten-werden-im-internet-gemobbt\/","title":{"rendered":"Alle Aktivisten werden im Internet gemobbt"},"content":{"rendered":"<p>Ich gebe einen weiteren Austausch aus einer Diskussion \u00fcber Tierversuche im Forum <em>Zeitwort.at<\/em> wieder:<\/p>\n<p>\u00a0<\/p>\n<p><a href=\"http:\/\/zeitwort.at\/index.php?page=Thread&amp;postID=185145#post185145\" target=\"_blank\">31.12.11 &#8211; Zitat von Renitenz<\/a>:<\/p>\n<p>Die ganze Emp\u00f6rung bringt nichts, weil die Experimente bei einem Verbot im Ausland durchgef\u00fchrt werden.<\/p>\n<p>\u00a0<\/p>\n<p><a href=\"http:\/\/zeitwort.at\/index.php?page=Thread&amp;postID=185150#post185150\" target=\"_blank\">31.12.11 \u2013 Zitat von Jocelyne Lopez<\/a>:<\/p>\n<p>Ich versuche etwas zu erreichen im Land wo ich lebe und wo ich Handlungs-m\u00f6glichkeiten habe, um es zu erreichen. Man kann nur etwas individuell tun, was im individuellen Handlungsbereich m\u00f6glich ist. Sonst sind es nur Stammtischgespr\u00e4che.<\/p>\n<p>Wenn jeder in seinem Land seine individuellen Handlungsm\u00f6glichkeiten in Anspruch nimmt und es erreicht, ist das Ziel vollst\u00e4ndig erreicht. Das Ablehnen der Tierversuche ist ein internationaler Trend. Auch im Ausland sind Tierversuchsgegner aktiv. In Neuseeland wurde zum Beispiel vor kurzem die &#8222;<em>Menschenrechte f\u00fcr Menschenaffen<\/em>&#8220; konstitutionell anerkannt, was sich auf die USA erweitert hat, siehe zum Beispiel <a href=\"http:\/\/www.heise.de\/tp\/artikel\/2\/2636\/1.html\" target=\"_blank\">hier<\/a>.<\/p>\n<p>Ein Kampf zeichnet sich nicht mit schnellen Erfolgen zum Ziel aus, leider, sondern durch Zwischenziele und Teilerfolge.<\/p>\n<h4 style=\"TEXT-ALIGN: center\"><a href=\"http:\/\/www.tag-zur-abschaffung-der-tierversuche.de\/\" target=\"_blank\"><span style=\"color: #3366ff;\">Internationaler Tag zur Abschaffung der Tierversuche<br \/>\nBremen 28.04.2012<\/span><\/a><\/h4>\n<p>\u00a0<\/p>\n<p><a href=\"http:\/\/zeitwort.at\/index.php?page=Thread&amp;postID=185151#post185151\" target=\"_blank\">31.12.11 \u2013 Zitat von Renitzenz<\/a>:<\/p>\n<p>Eben, da liegt die Crux begraben, denn es gibt schon viele Organisationen, denen man nur beitreten und in ihnen vortreten m\u00fcsste. Diese Handlungsm\u00f6glichkeit sch\u00f6pfst du nicht aus, sondern beschr\u00e4nkst dich auf Eigenbr\u00f6tlertum. Zudem ist auch deine Marke &#8211; n\u00e4mlich dein Name Jocelyne Lopes &#8211; unrettbar kaputt, weil alle Themen mit Streit verseucht sind.<\/p>\n<p>\u00a0<\/p>\n<p><a href=\"http:\/\/zeitwort.at\/index.php?page=Thread&amp;postID=185154#post185154\" target=\"_blank\">31.12.11 \u2013 Zitat von Jocelyne Lopez<\/a>:<\/p>\n<p>Ich bin \u00fcberhaupt keine &#8222;Eigenbr\u00f6tlerin&#8220;, das ist ein falscher Eindruck, sondern ich st\u00fctze mich auf Organisationen, die in diesem Bereich die \u00d6ffentlichkeitsarbeit leisten und die Informationen zur Verf\u00fcgung stellen. Wie Du es vielleicht hier im Forum gemerkt hast, habe ich sehr oft die Homepage, die Berichten und die Aktionen dieser Organisationen vorgestellt und verlinkt (Tierversuchsgegner-Vereine in Im- und Ausland), sowie in meinem Blog und in meiner Homepage auch vorgestellt und verlinkt. Das erwarten diese Organisationen von der &#8222;Basis&#8220;. Sie rechnen mit den Mitgliedern, Sympathisanten und Aktivisten im Internet, um ihre Informationen zu verbreiten und ihre Webseiten bekannt zu machen.<\/p>\n<p>Mein Name ist \u00fcbrigens \u00fcberhaupt nicht &#8222;<em>kaputt<\/em>&#8222;: Alle Tierversuchsgegner wissen, dass die Aktivisten gemobbt werden, ich bin nicht die einzige, weit verfehlt, das ist die Regel, das ist Gang und Gebe, alle Aktivisten werden gemobbt. Alle Tierversuchsgegner-Organisationen wissen es und sie sind wohl auch froh dar\u00fcber, das die Aktivisten &#8222;an der Front&#8220; die hei\u00dfen Kohlen aus dem Ofen holen und die gesellschaftliche Problematik ersichtlich machen, auch wenn sie sich die H\u00e4nde damit verbrennen. Ich arbeite au\u00dferdem zusammen mit Tierversuchsgegnern, die nicht im Internet t\u00e4tig sind, die jedoch wissen wie es im Internet l\u00e4uft und die deswegen meinen Einsatz bewundern, doch, ich bekomme schon Anerkennung von Tierversuchsgegnern, die meinen Einsatz sch\u00e4tzen und mich fragen, wie ich es im Internet \u00fcberhaupt aushalten kann. Aus dem Internet habe ich \u00fcbrigens auch pers\u00f6nliche Kontakte mit verschiedenen Tierversuchsgegnervereinen und einzelnen Tierversuchsgegnern. Kaum einer hat aber die Zeit oder \u00fcberhaupt die Motivation, sich mit den Abgr\u00fcnden des Internets zu besch\u00e4ftigen.<\/p>\n<p>In meinem Blog bestehen auch 90 % meiner Beitr\u00e4ge aus reinen Informationen \u00fcber die Tierexperimente und \u00fcber ihre Akteure (zum Beispiel \u00fcber Wolf Singer). Die Beitr\u00e4ge, die Streitigkeiten mit Mobber und Stalker betreffen sind in der Minderheit und dienen nur zum punktuellen Festhalten von Vorf\u00e4llen im Rahmen von laufenden juristischen Auseinandersetzungen (Esowatch &amp; co.).<\/p>\n<p>Mein Blog vermittelt also eine ganze Menge Informationen, sowohl \u00fcber die Tierversuche selbst als auch \u00fcber die gesellschaftlichen Umst\u00e4nde um die Tierversuche. Ich selektiere n\u00e4mlich f\u00fcr meinen Blog nur die wesentlichen Austausche aus Forendiskussionen, weil die Forendiskussionen selbst sehr schnell unlesbar werden und kaum ein Leser hat Lust und Zeit sich mit unlesbaren Forendiskussionen zu besch\u00e4ftigen. Meine Blog-Eintr\u00e4ge erreichen also eine Menge Leute, die sich sonst nicht in Forendiskussionen aufhalten. Meine Mobber und Stalker waren vor ein paar Jahren h\u00f6chstens ein Duzend von Figuren (jetzt nur noch zwei), daf\u00fcr ist die Anzahl der Leser meines Blogs nicht unbeachtlich f\u00fcr einen privaten Blog und auf jeden Fall h\u00f6her als die Anzahl der Leser von Foren-diskussionen. Ich versuche also das Beste aus den Abgr\u00fcnden des Internets zu machen und ich vermittle als vermeintliche &#8222;Eigenbr\u00f6tlerin&#8220; ziemlich vielen Menschen Informationen \u00fcber Tierversuche. Das Problem der Tierversuche ist ja nur ein Problem der Verbreitung der Informationen in der \u00d6ffentlichkeit, da die Massenmedien nicht zur Verf\u00fcgung der Tierversuchsgegner-Organisationen stehen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich gebe einen weiteren Austausch aus einer Diskussion \u00fcber Tierversuche im Forum Zeitwort.at wieder: \u00a0 31.12.11 &#8211; Zitat von Renitenz: Die ganze Emp\u00f6rung bringt nichts, weil die Experimente bei einem Verbot im Ausland durchgef\u00fchrt werden. \u00a0 31.12.11 \u2013 Zitat von Jocelyne Lopez: Ich versuche etwas zu erreichen im Land wo ich lebe und wo ich [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[9],"tags":[206,488,8,7,1334],"class_list":["post-5061","post","type-post","status-publish","format-standard","hentry","category-tierversuche-abschaffen","tag-alpha-centauri","tag-esowatch","tag-tierrechte","tag-tierschutz","tag-tierversuche-abschaffen"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts\/5061"}],"collection":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/comments?post=5061"}],"version-history":[{"count":0,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts\/5061\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/media?parent=5061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/categories?post=5061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/tags?post=5061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}