{"id":4513,"date":"2009-10-16T07:07:27","date_gmt":"2009-10-16T06:07:27","guid":{"rendered":"https:\/\/www.jocelyne-lopez.de\/blog\/?p=4513"},"modified":"2009-10-16T07:08:06","modified_gmt":"2009-10-16T06:08:06","slug":"wie-kommt-man-blos-als-uberforderte-aus-dem-unverstandlichen","status":"publish","type":"post","link":"https:\/\/www.jocelyne-lopez.de\/blog\/2009\/10\/wie-kommt-man-blos-als-uberforderte-aus-dem-unverstandlichen\/","title":{"rendered":"Wie kommt man blo\u00df als \u00dcberforderte aus dem Unverst\u00e4ndlichen?"},"content":{"rendered":"<p>Man m\u00f6chte meinen, dass man seinen Verstand einsetzen mu\u00df, um die Relativit\u00e4ts-theorie zu verstehen:<\/p>\n<p style=\"padding-left: 60px;\"><em>\u201eMeine Hoffnung ist, da\u00df in nicht allzu ferner Zukunft die Ideen der Relativit\u00e4tstheorie endg\u00fcltig den Schleier des Magischen, Geheimnisvollen und Unverst\u00e4ndlichen verlieren, also ein Teil der Allgemeinbildung werden, und da\u00df dieses Buch hierzu einen Beitrag leistet.\u201c<\/em><\/p>\n<p style=\"padding-left: 60px;\">H. Fritzsch: Eine Formel ver\u00e4ndert die Welt. 3. Aufl. M\u00fcnchen (usw.): Piper 1996, S. 20.<br \/>\n\u00a0<\/p>\n<p>Weit verfehlt: Um aus der Welt\u00a0des Magischen, des Geheimnisvollen und des Unverst\u00e4ndlichen endg\u00fcltig\u00a0herauszukommen mu\u00df man\u00a0ganz im Gegenteil seinen Verstand opfern, womit die Erkenntnisse der modernen Physik bedauerlicherweise nicht zu verstehen sind:\u00a0\n<\/p>\n<p style=\"padding-left: 60px;\">\u201e<em>Beim Umsturz des alten Weltbildes &#8211; einem Paradigmenwandel, der unser Wirklichkeitsverst\u00e4ndnis drastisch ver\u00e4ndert &#8211; ist der \u2018gesunde Menschenverstand\u2019 das Opferkalb.\u201c &#8211; \u201eEinige sind in ihrem Blick auf die Wirklichkeit dem \u2018gesunden Menschenverstand\u2019 derart verhaftet, da\u00df sie selbst die Erkenntnisse der modernen Physik anzweifeln\u201c.<\/em>\u00a0<\/p>\n<p style=\"padding-left: 60px;\">Davies, Paul C. W.: Auf dem Weg zur Weltformel \/ Paul Davies &amp; John Gribbin. Berlin: Byblos Verl. 1997. S. 17 u. 24.<\/p>\n<p>\u00a0<\/p>\n<p>Was nun? Verstehen ohne Verstand oder Magie ohne Wirklichkeitsverst\u00e4ndnis?<\/p>\n<p>Hmm\u2026 Ich f\u00fcrchte, ich mu\u00df noch \u00fcben\u2026 ich bin wohl noch <a href=\"https:\/\/www.jocelyne-lopez.de\/blog\/2009\/10\/wir-sind-alle-dumm-und-uberfordert-pech-nur-die-relativisten-nicht\/\" target=\"_blank\">\u00dcberforderte<\/a> 1. Stufe.\u00a0<\/p>\n<p>(Jocelyne Lopez)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Man m\u00f6chte meinen, dass man seinen Verstand einsetzen mu\u00df, um die Relativit\u00e4ts-theorie zu verstehen: \u201eMeine Hoffnung ist, da\u00df in nicht allzu ferner Zukunft die Ideen der Relativit\u00e4tstheorie endg\u00fcltig den Schleier des Magischen, Geheimnisvollen und Unverst\u00e4ndlichen verlieren, also ein Teil der Allgemeinbildung werden, und da\u00df dieses Buch hierzu einen Beitrag leistet.\u201c H. Fritzsch: Eine Formel ver\u00e4ndert [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[13],"tags":[1336],"class_list":["post-4513","post","type-post","status-publish","format-standard","hentry","category-kritik-der-relativitatstheorie","tag-kritik-der-relativitatstheorie"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts\/4513"}],"collection":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/comments?post=4513"}],"version-history":[{"count":0,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts\/4513\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/media?parent=4513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/categories?post=4513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/tags?post=4513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}