{"id":443,"date":"2008-10-10T17:24:26","date_gmt":"2008-10-10T16:24:26","guid":{"rendered":"https:\/\/www.jocelyne-lopez.de\/blog\/?p=443"},"modified":"2008-10-10T17:24:26","modified_gmt":"2008-10-10T16:24:26","slug":"die-langenkontraktion-existiert-nicht","status":"publish","type":"post","link":"https:\/\/www.jocelyne-lopez.de\/blog\/2008\/10\/die-langenkontraktion-existiert-nicht\/","title":{"rendered":"Die L\u00e4ngenkontraktion existiert nicht"},"content":{"rendered":"<p>Ich komme zur\u00fcck auf das\u00a0<a target=\"_blank\" href=\"https:\/\/www.jocelyne-lopez.de\/blog\/?p=435\">Gartenzaun-Paradoxon <\/a>von Peter Ripota in diesem Blog.<br \/>\nDieses Paradoxon l\u00e4sst sich nur l\u00f6sen, wenn die L\u00e4ngenkontraktion nur scheinbar ist.<\/p>\n<p>Und die L\u00e4ngenkontraktion ist ja offiziell auch nur scheinbar: Dr. Markus P\u00f6ssel, als autorisierter und qualifizierter Ansprechpartner f\u00fcr alle Fragen \u00fcber die Relativit\u00e4tstheorie beim Max-Planck-Institut f\u00fcr Gravitationsphysik\/Albert Einstein Institut\/Einstein Online\u00a0hat ja in seiner <a target=\"_blank\" href=\"https:\/\/www.jocelyne-lopez.de\/blog\/?p=405\">E-Mail vom 17.08.08<\/a>\u00a0best\u00e4tigt, dass an <strong>der materiellen L\u00e4nge des Objektes sich nichts \u00e4ndert<\/strong>:<\/p>\n<blockquote>\n<blockquote><p><strong>Zitat Dr. Markus P\u00f6ssel:<\/strong><\/p>\n<p>Die Laengenkontraktion geht nicht mit materiellen Veraenderungen des Koerpers einher.<\/p>\n<p><font color=\"#ffffff\">&#8212;<\/font><\/p><\/blockquote>\n<\/blockquote>\n<p>Und hier gelten nat\u00fcrlich die Aussagen von Peter Ripota:<\/p>\n<blockquote>\n<blockquote><p><strong>Zitat\u00a0Peter Ripota<\/strong>:<\/p>\n<p>Das Wechseln des Standpunkts macht etwas m\u00f6glich, was vorher unm\u00f6glich war. Aber, ist das Ganze vielleicht nur Illusion? Dann muss auch, aus Symmetriegr\u00fcnden, das Zwillingsparadoxon Illusion sein, und wir brauchen uns um beides keine Gedanken machen. Mit anderen Worten: W\u00e4ren die Effekte nur scheinbar, w\u00e4re auch die Relativit\u00e4tstheorie \u00fcberfl\u00fcssig, denn Physik besch\u00e4ftigt sich mit Sein, nicht mit Schein.<\/p>\n<p><font color=\"#ffffff\">&#8212;<\/font><\/p><\/blockquote>\n<\/blockquote>\n<p>Ja, was tangiert hier uns was scheinbar ist? Wir wollen doch Physik betreiben, und nicht Biologie, Psychologie, Esoterik oder Hokuspokus.<\/p>\n<p>(Jocelyne Lopez)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich komme zur\u00fcck auf das\u00a0Gartenzaun-Paradoxon von Peter Ripota in diesem Blog. Dieses Paradoxon l\u00e4sst sich nur l\u00f6sen, wenn die L\u00e4ngenkontraktion nur scheinbar ist. Und die L\u00e4ngenkontraktion ist ja offiziell auch nur scheinbar: Dr. Markus P\u00f6ssel, als autorisierter und qualifizierter Ansprechpartner f\u00fcr alle Fragen \u00fcber die Relativit\u00e4tstheorie beim Max-Planck-Institut f\u00fcr Gravitationsphysik\/Albert Einstein Institut\/Einstein Online\u00a0hat ja in [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[13],"tags":[440,1336,183,177,258],"class_list":["post-443","post","type-post","status-publish","format-standard","hentry","category-kritik-der-relativitatstheorie","tag-gartenzaun-paradoxon","tag-kritik-der-relativitatstheorie","tag-markus-possel","tag-peter-ripota","tag-relativitatstheorie"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts\/443"}],"collection":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/comments?post=443"}],"version-history":[{"count":0,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/posts\/443\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/media?parent=443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/categories?post=443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jocelyne-lopez.de\/blog\/wp-json\/wp\/v2\/tags?post=443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}